{"id":61675,"date":"2022-08-08T15:29:13","date_gmt":"2022-08-08T15:29:13","guid":{"rendered":"https:\/\/ikosresorts.com\/?page_id=61675"},"modified":"2026-07-03T10:19:53","modified_gmt":"2026-07-03T10:19:53","slug":"offers","status":"publish","type":"page","link":"https:\/\/ikosresorts.com\/fr\/offers\/","title":{"rendered":"Offers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"61675\" class=\"elementor elementor-61675 elementor-22\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64e1f427 elementor-section-full_width elementor-section-height-min-height hero-single elementor-section-height-default elementor-section-items-middle\" data-id=\"64e1f427\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:58328,&quot;url&quot;:&quot;https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Image0056-1.jpg&quot;}],&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b03f7b1 hero-column\" data-id=\"b03f7b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4044273 elementor-section-full_width hero-group-titles elementor-section-height-default elementor-section-height-default\" data-id=\"4044273\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-24b38c09\" data-id=\"24b38c09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c243945 hero2-title elementor-widget elementor-widget-heading\" data-id=\"5c243945\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Offres<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7515a8c0 hero-explore-desktop elementor-section-height-min-height elementor-hidden-mobile elementor-section-boxed elementor-section-height-default\" data-id=\"7515a8c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-46a0c787 hero-column\" data-id=\"46a0c787\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-336f351f elementor-widget elementor-widget-heading\" data-id=\"336f351f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explore<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c98665 elementor-widget elementor-widget-image\" data-id=\"51c98665\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"26\" height=\"30\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png\" class=\"attachment-large size-large wp-image-9213\" alt=\"arrow-down\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f2d4dac hero-explore-mobile elementor-section-height-min-height elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-laptop elementor-section-boxed elementor-section-height-default\" data-id=\"6f2d4dac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1583f8b4 hero-column\" data-id=\"1583f8b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36e03962 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"36e03962\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"26\" height=\"30\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png\" class=\"attachment-large size-large wp-image-9213\" alt=\"arrow-down\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5120192 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"5120192\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Swipe to explore<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8db66a ikos-article-media-text offers-row-section elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8db66a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e220b19\" data-id=\"e220b19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ab0db6 elementor-widget elementor-widget-ikos-image-slider\" data-id=\"4ab0db6\" data-element_type=\"widget\" data-widget_type=\"ikos-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"ikos-image-slider\">\r\n            <div class=\"swiper \">\r\n                <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                    <div class=\"swiper-slide-inner\">\r\n                                        <img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"580\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2025\/09\/Early-Booking-1024x742.jpg\" class=\"center-center\" alt=\"Early-Booking\" \/>                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"ikos-slide-pagination pagination-show-hide\">\r\n                    <div class=\"slider-pagination\"><\/div>\r\n                <\/div>\r\n\r\n                <div class=\"ikos-slider-nav navigation-desktop\">\r\n                    <div class=\"slider-button-prev\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"m1.905 12.874 11.36 11.36-.53.53-12-12L.47 12.5l.265-.266 12-12 .53.53-11.36 11.36H48.5v.75H1.905Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                    <div class=\"slider-button-next\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M47.095 12.126 35.735.766l.53-.53 12 12 .265.264-.265.266-12 12-.53-.53 11.36-11.36H.5v-.75h46.595Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c108466 ikos-article-text-col left-text\" data-id=\"c108466\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07c6be7 elementor-widget elementor-widget-heading\" data-id=\"07c6be7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9servations Anticip\u00e9es<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37b53de elementor-widget elementor-widget-text-editor\" data-id=\"37b53de\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Les l\u00e8ve-t\u00f4t b\u00e9n\u00e9ficient des meilleures offres. En r\u00e9servant directement avec Ikos Resorts, vous b\u00e9n\u00e9ficierez d&#8217;encore plus d&#8217;avantages tels que le s\u00e9jour gratuit pour votre premier enfant et des transferts gratuits pour toute r\u00e9servation de cinq nuits ou plus.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-185bb25 border-blue-btn elementor-widget elementor-widget-button\" data-id=\"185bb25\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ikosresorts.com\/fr\/offers\/early-booking\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc10b01 ikos-article-media-text offers-row-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc10b01\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-16ae594 ikos-article-text-col\" data-id=\"16ae594\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9257b9a elementor-widget elementor-widget-heading\" data-id=\"9257b9a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Offres Sp\u00e9ciales<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f3da6 elementor-widget elementor-widget-text-editor\" data-id=\"a0f3da6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Certains \u00e9t\u00e9s vous marquent \u00e0 jamais. Entre menus \u00e9toil\u00e9s au guide Michelin et couchers de soleil m\u00e9diterran\u00e9ens, chaque instant se vit avec l\u00e9g\u00e8ret\u00e9 et chaque souvenir se tisse entre les g\u00e9n\u00e9rations.<\/p><p>Profitez des meilleures offres estivales. R\u00e9servez vos vacances pour l\u2019\u00e9t\u00e9 2026 chez Ikos Resorts et b\u00e9n\u00e9ficiez de transferts gratuits pour les r\u00e9servations directes en ligne.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeaa2cb border-blue-btn elementor-widget elementor-widget-button\" data-id=\"eeaa2cb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/offers\/special-offers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ffa2596\" data-id=\"ffa2596\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b340b0 elementor-widget elementor-widget-ikos-image-slider\" data-id=\"8b340b0\" data-element_type=\"widget\" data-widget_type=\"ikos-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"ikos-image-slider\">\r\n            <div class=\"swiper \">\r\n                <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                    <div class=\"swiper-slide-inner\">\r\n                                        <img decoding=\"async\" width=\"800\" height=\"580\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2025\/12\/Special-Offers-1024x742.jpg\" class=\"center-center\" alt=\"Special-Offers.jpg\" \/>                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"ikos-slide-pagination pagination-show-hide\">\r\n                    <div class=\"slider-pagination\"><\/div>\r\n                <\/div>\r\n\r\n                <div class=\"ikos-slider-nav navigation-desktop\">\r\n                    <div class=\"slider-button-prev\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"m1.905 12.874 11.36 11.36-.53.53-12-12L.47 12.5l.265-.266 12-12 .53.53-11.36 11.36H48.5v.75H1.905Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                    <div class=\"slider-button-next\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M47.095 12.126 35.735.766l.53-.53 12 12 .265.264-.265.266-12 12-.53-.53 11.36-11.36H.5v-.75h46.595Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2e30f9 ikos-article-media-text offers-row-section elementor-reverse-mobile elementor-reverse-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2e30f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c52571b\" data-id=\"6c52571b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50befc61 elementor-widget elementor-widget-ikos-image-slider\" data-id=\"50befc61\" data-element_type=\"widget\" data-widget_type=\"ikos-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"ikos-image-slider\">\r\n            <div class=\"swiper \">\r\n                <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                    <div class=\"swiper-slide-inner\">\r\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"580\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2025\/09\/Repeaters-Discount-1024x742.jpg\" class=\"center-center\" alt=\"Repeaters-Discount\" \/>                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"ikos-slide-pagination pagination-show-hide\">\r\n                    <div class=\"slider-pagination\"><\/div>\r\n                <\/div>\r\n\r\n                <div class=\"ikos-slider-nav navigation-desktop\">\r\n                    <div class=\"slider-button-prev\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"m1.905 12.874 11.36 11.36-.53.53-12-12L.47 12.5l.265-.266 12-12 .53.53-11.36 11.36H48.5v.75H1.905Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                    <div class=\"slider-button-next\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M47.095 12.126 35.735.766l.53-.53 12 12 .265.264-.265.266-12 12-.53-.53 11.36-11.36H.5v-.75h46.595Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2155122c ikos-article-text-col\" data-id=\"2155122c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2832517d elementor-widget elementor-widget-heading\" data-id=\"2832517d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantage Fid\u00e9lit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56dcb15 elementor-widget elementor-widget-text-editor\" data-id=\"56dcb15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pour remercier tous nos h\u00f4tes qui reviennent \u00e0 Ikos Resorts ann\u00e9e apr\u00e8s ann\u00e9e, nous offrons 10 % de r\u00e9duction sur l&#8217;h\u00e9bergement* (non cumulable avec d&#8217;autres offres sp\u00e9ciales) ainsi que des transferts gratuits.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53bd98b border-blue-btn elementor-widget elementor-widget-button\" data-id=\"53bd98b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ikosresorts.com\/fr\/offers\/repeaters-discount\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cdcf7ab ikos-article-media-text offers-row-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cdcf7ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-119f3587 ikos-article-text-col left-text\" data-id=\"119f3587\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cb95aa3 elementor-widget elementor-widget-heading\" data-id=\"5cb95aa3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Premier Enfant Inclus<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59969fea elementor-widget elementor-widget-text-editor\" data-id=\"59969fea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous souhaitons que vous veniez avec vos enfants, vos familles ! C&#8217;est pourquoi le premier enfant jusqu&#8217;\u00e0 l&#8217;\u00e2ge de 11 ans s\u00e9journe gratuitement dans nos resorts.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdf1309 border-blue-btn elementor-widget elementor-widget-button\" data-id=\"bdf1309\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ikosresorts.com\/fr\/offers\/first-child-free\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-667b786e\" data-id=\"667b786e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3931486e elementor-widget elementor-widget-ikos-image-slider\" data-id=\"3931486e\" data-element_type=\"widget\" data-widget_type=\"ikos-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"ikos-image-slider\">\r\n            <div class=\"swiper \">\r\n                <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                    <div class=\"swiper-slide-inner\">\r\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"580\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2025\/09\/First-Child-Free-1024x742.jpg\" class=\"center-center\" alt=\"First-Child-Free\" \/>                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"ikos-slide-pagination pagination-show-hide\">\r\n                    <div class=\"slider-pagination\"><\/div>\r\n                <\/div>\r\n\r\n                <div class=\"ikos-slider-nav navigation-desktop\">\r\n                    <div class=\"slider-button-prev\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"m1.905 12.874 11.36 11.36-.53.53-12-12L.47 12.5l.265-.266 12-12 .53.53-11.36 11.36H48.5v.75H1.905Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                    <div class=\"slider-button-next\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M47.095 12.126 35.735.766l.53-.53 12 12 .265.264-.265.266-12 12-.53-.53 11.36-11.36H.5v-.75h46.595Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ad80209 ikos-article-media-text offers-row-section elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ad80209\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ecbe862\" data-id=\"ecbe862\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f6d889b elementor-widget elementor-widget-ikos-image-slider\" data-id=\"5f6d889b\" data-element_type=\"widget\" data-widget_type=\"ikos-image-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n        <div class=\"ikos-image-slider\">\r\n            <div class=\"swiper \">\r\n                <div class=\"swiper-wrapper\">\r\n                                                    <div class=\"swiper-slide\">\r\n                                    <div class=\"swiper-slide-inner\">\r\n                                        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"580\" src=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2025\/09\/Free-Transfers-1024x742.jpg\" class=\"center-center\" alt=\"Free-Transfers\" \/>                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"ikos-slide-pagination pagination-show-hide\">\r\n                    <div class=\"slider-pagination\"><\/div>\r\n                <\/div>\r\n\r\n                <div class=\"ikos-slider-nav navigation-desktop\">\r\n                    <div class=\"slider-button-prev\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"m1.905 12.874 11.36 11.36-.53.53-12-12L.47 12.5l.265-.266 12-12 .53.53-11.36 11.36H48.5v.75H1.905Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                    <div class=\"slider-button-next\">\r\n                        <button>\r\n                            <svg fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 49 25\">\r\n                                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M47.095 12.126 35.735.766l.53-.53 12 12 .265.264-.265.266-12 12-.53-.53 11.36-11.36H.5v-.75h46.595Z\" fill=\"currentColor\"\/>\r\n                            <\/svg>\r\n                        <\/button>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c00217a ikos-article-text-col left-text\" data-id=\"2c00217a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac35b52 elementor-widget elementor-widget-heading\" data-id=\"ac35b52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transferts Offerts<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c5b0150 elementor-widget elementor-widget-text-editor\" data-id=\"5c5b0150\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>R\u00e9servez un s\u00e9jour de 5 nuits ou plus directement avec Ikos et b\u00e9n\u00e9ficiez des transferts a\u00e9roport gratuits.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9d4f9c border-blue-btn elementor-widget elementor-widget-button\" data-id=\"e9d4f9c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ikosresorts.com\/fr\/offers\/free-transfers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b13b8f2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b13b8f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-715f56b\" data-id=\"715f56b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3baebf9 elementor-widget elementor-widget-global elementor-global-87448 elementor-widget-template\" data-id=\"3baebf9\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"87604\" class=\"elementor elementor-87604 elementor-87414\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1627e3d elementor-section-height-min-height elementor-section-content-middle resorts-sub-menu elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1627e3d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7106496\" data-id=\"7106496\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34d9f8a elementor-widget elementor-widget-heading\" data-id=\"34d9f8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/\">Offres<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0ee138a\" data-id=\"0ee138a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b02047a elementor-nav-menu__align-center resorts-sub-menu-nav elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"b02047a\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/elementor\/css\/custom-pro-widget-nav-menu.min.css?ver=1742458639\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-slide\">\n\t\t\t\t<ul id=\"menu-1-b02047a\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63802\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/special-offers\/\" class=\"elementor-item\">Offres Sp\u00e9ciales<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63803\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/first-child-free\/\" class=\"elementor-item\">Premier Enfant Inclus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63804\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/repeaters-discount\/\" class=\"elementor-item\">Avantage Fid\u00e9lit\u00e9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63805\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/free-transfers\/\" class=\"elementor-item\">Transferts Offerts<\/a><\/li>\n<li class=\"hidemenu menu-item menu-item-type-post_type menu-item-object-page menu-item-63806\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/early-booking\/\" class=\"elementor-item\">R\u00e9servations Anticip\u00e9es<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-b02047a\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63802\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/special-offers\/\" class=\"elementor-item\" tabindex=\"-1\">Offres Sp\u00e9ciales<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63803\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/first-child-free\/\" class=\"elementor-item\" tabindex=\"-1\">Premier Enfant Inclus<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63804\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/repeaters-discount\/\" class=\"elementor-item\" tabindex=\"-1\">Avantage Fid\u00e9lit\u00e9<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-63805\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/free-transfers\/\" class=\"elementor-item\" tabindex=\"-1\">Transferts Offerts<\/a><\/li>\n<li class=\"hidemenu menu-item menu-item-type-post_type menu-item-object-page menu-item-63806\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/early-booking\/\" class=\"elementor-item\" tabindex=\"-1\">R\u00e9servations Anticip\u00e9es<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75b0231 elementor-section-height-min-height elementor-section-content-middle resorts-sub-menu elementor-hidden-desktop elementor-hidden-laptop elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"75b0231\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bdfdf90\" data-id=\"bdfdf90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-231b19d elementor-widget elementor-widget-heading\" data-id=\"231b19d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ikosresorts.com\/fr\/offers\/\">Offres<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f8638a\" data-id=\"6f8638a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fbd9c5 elementor-mobile-align-right elementor-tablet-align-right normal-button elementor-widget elementor-widget-button\" data-id=\"5fbd9c5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MTk3MTAsInRvZ2dsZSI6dHJ1ZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M12.375 11.625V0H11.625V11.625H0V12.375H11.625V24H12.375V12.375H24V11.625H12.375Z\" fill=\"#22292B\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MENU<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b8e907 elementor-mobile-align-right elementor-tablet-align-right elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile normal-button elementor-widget elementor-widget-button\" data-id=\"0b8e907\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MTk3MTAsInRvZ2dsZSI6dHJ1ZX0%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.46924 8.99951L0.734431 1.26471L1.26476 0.734375L8.99957 8.46918L16.7344 0.734379L17.2647 1.26471L9.5299 8.99951L17.2648 16.7344L16.7344 17.2647L8.99957 9.52984L1.26471 17.2647L0.734375 16.7344L8.46924 8.99951Z\" fill=\"#22292B\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CLOSE MENU<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Offres Explore Swipe to explore R\u00e9servations Anticip\u00e9es Les l\u00e8ve-t\u00f4t b\u00e9n\u00e9ficient des meilleures offres. En r\u00e9servant directement avec Ikos Resorts, vous b\u00e9n\u00e9ficierez d&#8217;encore plus d&#8217;avantages tels que le s\u00e9jour gratuit pour votre premier enfant et des transferts gratuits pour toute r\u00e9servation de cinq nuits ou plus. D\u00e9couvrir Plus Offres Sp\u00e9ciales Certains \u00e9t\u00e9s vous marquent \u00e0 jamais. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-61675","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vacances Offres | Ikos Resorts<\/title>\n<meta name=\"description\" content=\"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ikosresorts.com\/fr\/offers\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offers\" \/>\n<meta property=\"og:description\" content=\"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ikosresorts.com\/fr\/offers\/\" \/>\n<meta property=\"og:site_name\" content=\"Ikos Resorts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ikosresorts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T10:19:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png\" \/>\n\t<meta property=\"og:image:width\" content=\"26\" \/>\n\t<meta property=\"og:image:height\" content=\"30\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ikosresorts\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/\",\"url\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/\",\"name\":\"Vacances Offres | Ikos Resorts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/arrow-down.png\",\"datePublished\":\"2022-08-08T15:29:13+00:00\",\"dateModified\":\"2026-07-03T10:19:53+00:00\",\"description\":\"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/#breadcrumb\"},\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/arrow-down.png\",\"contentUrl\":\"https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/arrow-down.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/offers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ikosresorts.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/\",\"name\":\"Ikos Resorts\",\"description\":\"Live The Ikos Way\",\"publisher\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#organization\",\"name\":\"Ikos Resorts\",\"url\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo_Ikos_White.svg\",\"contentUrl\":\"https:\\\/\\\/ikosresorts.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Logo_Ikos_White.svg\",\"width\":100,\"height\":61,\"caption\":\"Ikos Resorts\"},\"image\":{\"@id\":\"https:\\\/\\\/ikosresorts.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ikosresorts\",\"https:\\\/\\\/x.com\\\/ikosresorts\",\"https:\\\/\\\/www.instagram.com\\\/ikosresorts\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@ikosresortsofficial\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ikosresortsofficial\"],\"description\":\"No two perfect days at Ikos ever look the same. That\u2019s why every resort offers a world of thoughtfully curated experience. From padel, to reformer pilates, football to discovering the authentic character of each destination through Local Discovery. Everything designed so you can explore more freely, connect more deeply, and follow wherever the day takes you.\",\"email\":\"info@ikosresorts.com\",\"telephone\":\"+30 2374110750\",\"legalName\":\"Ikos Resorts\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vacances Offres | Ikos Resorts","description":"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ikosresorts.com\/fr\/offers\/","og_locale":"fr_FR","og_type":"article","og_title":"Offers","og_description":"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.","og_url":"https:\/\/ikosresorts.com\/fr\/offers\/","og_site_name":"Ikos Resorts","article_publisher":"https:\/\/www.facebook.com\/ikosresorts","article_modified_time":"2026-07-03T10:19:53+00:00","og_image":[{"width":26,"height":30,"url":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ikosresorts","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ikosresorts.com\/fr\/offers\/","url":"https:\/\/ikosresorts.com\/fr\/offers\/","name":"Vacances Offres | Ikos Resorts","isPartOf":{"@id":"https:\/\/ikosresorts.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ikosresorts.com\/fr\/offers\/#primaryimage"},"image":{"@id":"https:\/\/ikosresorts.com\/fr\/offers\/#primaryimage"},"thumbnailUrl":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png","datePublished":"2022-08-08T15:29:13+00:00","dateModified":"2026-07-03T10:19:53+00:00","description":"Profitez de transferts gratuits et de r\u00e9ductions pour les r\u00e9servations anticip\u00e9es. D\u00e9couvrez nos offres pour les meilleures vacances chez Ikos Resorts.","breadcrumb":{"@id":"https:\/\/ikosresorts.com\/fr\/offers\/#breadcrumb"},"inLanguage":"fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ikosresorts.com\/fr\/offers\/"]}]},{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/ikosresorts.com\/fr\/offers\/#primaryimage","url":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png","contentUrl":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2022\/10\/arrow-down.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ikosresorts.com\/fr\/offers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ikosresorts.com\/"},{"@type":"ListItem","position":2,"name":"Offers"}]},{"@type":"WebSite","@id":"https:\/\/ikosresorts.com\/fr\/#website","url":"https:\/\/ikosresorts.com\/fr\/","name":"Ikos Resorts","description":"Live The Ikos Way","publisher":{"@id":"https:\/\/ikosresorts.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ikosresorts.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr"},{"@type":"Organization","@id":"https:\/\/ikosresorts.com\/fr\/#organization","name":"Ikos Resorts","url":"https:\/\/ikosresorts.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/ikosresorts.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2023\/01\/Logo_Ikos_White.svg","contentUrl":"https:\/\/ikosresorts.com\/wp-content\/uploads\/2023\/01\/Logo_Ikos_White.svg","width":100,"height":61,"caption":"Ikos Resorts"},"image":{"@id":"https:\/\/ikosresorts.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ikosresorts","https:\/\/x.com\/ikosresorts","https:\/\/www.instagram.com\/ikosresorts\/","https:\/\/www.tiktok.com\/@ikosresortsofficial","https:\/\/www.youtube.com\/user\/ikosresortsofficial"],"description":"No two perfect days at Ikos ever look the same. That\u2019s why every resort offers a world of thoughtfully curated experience. From padel, to reformer pilates, football to discovering the authentic character of each destination through Local Discovery. Everything designed so you can explore more freely, connect more deeply, and follow wherever the day takes you.","email":"info@ikosresorts.com","telephone":"+30 2374110750","legalName":"Ikos Resorts"}]}},"_links":{"self":[{"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/pages\/61675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/comments?post=61675"}],"version-history":[{"count":15,"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/pages\/61675\/revisions"}],"predecessor-version":[{"id":179313,"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/pages\/61675\/revisions\/179313"}],"wp:attachment":[{"href":"https:\/\/ikosresorts.com\/fr\/wp-json\/wp\/v2\/media?parent=61675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}